{"id":2515,"date":"2024-03-03T18:01:21","date_gmt":"2024-03-03T17:01:21","guid":{"rendered":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/?p=2515"},"modified":"2024-03-03T18:02:37","modified_gmt":"2024-03-03T17:02:37","slug":"fahrten-und-veranstaltungen-2024","status":"publish","type":"post","link":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/2024\/03\/03\/fahrten-und-veranstaltungen-2024\/","title":{"rendered":"Fahrten und Veranstaltungen 2024"},"content":{"rendered":"<p>Liebe Seniorinnen und Senioren,<br \/>\nauch in diesem Jahr freut sich der Seniorenbeirat, Ihnen\/Euch einige <strong>Fahrten und Veranstaltungen<\/strong> anbieten zu k\u00f6nnen.<\/p>\n<p>Jeden 1. Mittwoch im Monat findet im Pastor-Pfeifer-Haus ab 15 Uhr der <strong>Kaffeenachmittag<\/strong> statt. (Ausnahme nicht am 1.Mai).<br \/>\nJeden 3. Mittwoch im Monat beginnt der <strong>Spielenachmittag<\/strong> ab 15 Uhr im Strohdachhaus.<\/p>\n<p>Der Seniorenbeirat bietet folgende Fahrten ab der Schwimmhalle in Niendorf\/Ostsee an:<br \/>\nDienstag, <strong>21.05. <\/strong>| 09.45 Uhr zum<strong> Rapsbl\u00fctenfest nach Fehmarn mit Inselrundfahrt und Spargelessen als Mittagstisch<\/strong>.<br \/>\nAnmeldung und Bezahlung am 3. April. Kaffeeteilnehmer ab 15 Uhr, die anderen in der Zeit von 13.45 &#8211; 14.15 Uhr.<\/p>\n<p>Donnerstag, <strong>15.08.<\/strong> | 08.15 Uhr <strong>Fahrt in die Probstei<\/strong>, Besichtigung diverser Strohfiguren und Kaffeetrinken.<br \/>\nKostenbeitrag 35 \u20ac<\/p>\n<p>Freitag, <strong>11.10.<\/strong> | 08.30 Uhr<strong> Fahrt nach Dithmarschen, Rundfahrt und Kohlessen<\/strong>, Besuch des G\u00e4nsemarktes.<br \/>\nKostenbeitrag 40 \u20ac. Weitere Informationen werden wie immer im Reporter zeitnah bekanntgegeben.<\/p>\n<p>Alle Termine sind unter Vorbehalt. Die Anmeldungen und Bezahlung finden jeweils an den verschiedenen Kaffeenachmittagen statt.<\/p>\n<p><strong>Veranstaltungen:<\/strong><br \/>\nSamstag,<strong> 08.06.<\/strong> <strong>B\u00fcrgerfest der Gemeinde<\/strong> im Timmendorfer Strandpark von 11 \u2013 17 Uhr<br \/>\nSamstag, 27.07. <strong>Sommerfest<\/strong> an der Mensa der GGS Europaschule Timmendorfer Strand, Beginn 15.30 Uhr<br \/>\nFreitag, 20.09. <strong>Einweihung der neuen Seebr\u00fccke<\/strong><br \/>\nMittwoch, <strong>23.10.<\/strong> | 09.30 Uhr <strong>Gemeindefr\u00fchst\u00fcck<\/strong> im Saal des Haus des Kurgastes in Niendorf\/Ostsee mit der Wahl des neuen Seniorenbeirates.<br \/>\nSamstag, <strong>23.11.<\/strong> | 12.30 Uhr. <strong>Beginn des Entenessens<\/strong> in der Mensa der GGS Europaschule Timmendorfer Strand<br \/>\nAm Samstag,<strong> 9.11.<\/strong> findet in der Strandhalle in Gr\u00f6mitz ein <strong>Dankesch\u00f6n-Konzert mit der Big-Band der Uni Kiel<\/strong> bei freiem Eintritt statt.<br \/>\nSamstag, <strong>14.12.<\/strong> findet ab 15.30 Uhr eine <strong>Weihnachtsfeier<\/strong> statt.<\/p>\n<p>Fehlende Angaben zu Zeiten und Kostenbeitr\u00e4ge werden zum sp\u00e4teren Zeitpunkt noch im Schaukasten am Strohdachhaus oder im Reporter bekannt gemacht.<br \/>\nDer Seniorenbeirat w\u00fcnscht allen Teilnehmerinnen und Teilnehmer eine rege Beteiligung und Freude an den Unternehmungen.<\/p>\n<p>Ihr Seniorenbeirat Timmendorfer Strand<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Seniorinnen und Senioren, auch in diesem Jahr freut sich der Seniorenbeirat, Ihnen\/Euch einige Fahrten und Veranstaltungen anbieten zu k\u00f6nnen. Jeden 1. Mittwoch im Monat findet im Pastor-Pfeifer-Haus ab 15 &#8230;<\/p>\n","protected":false},"author":1,"featured_media":1696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,19],"tags":[],"class_list":["post-2515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-termine"],"_links":{"self":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/posts\/2515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/comments?post=2515"}],"version-history":[{"count":1,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/posts\/2515\/revisions"}],"predecessor-version":[{"id":2516,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/posts\/2515\/revisions\/2516"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/media\/1696"}],"wp:attachment":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/media?parent=2515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/categories?post=2515"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/tags?post=2515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}