{"id":19,"count":112,"description":"","link":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/category\/termine\/","name":"Termine","slug":"termine","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/luebecker-bucht-lokal.de\/senioren-beirat\/wp-json\/wp\/v2\/posts?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}